{"id":124,"date":"2025-09-17T12:00:21","date_gmt":"2025-09-17T12:00:21","guid":{"rendered":"https:\/\/sig.fmipa.unm.ac.id\/?page_id=124"},"modified":"2025-10-08T05:28:15","modified_gmt":"2025-10-08T05:28:15","slug":"gpm","status":"publish","type":"page","link":"https:\/\/sig.fmipa.unm.ac.id\/fr\/gpm\/","title":{"rendered":"Gugus Penjaminan Mutu"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":239059,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-124","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"fr","enabled_languages":["en","es","de","fr","ru"],"languages":{"en":{"title":true,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/pages\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/users\/239059"}],"replies":[{"embeddable":true,"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/comments?post=124"}],"version-history":[{"count":5,"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/pages\/124\/revisions"}],"predecessor-version":[{"id":191,"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/pages\/124\/revisions\/191"}],"wp:attachment":[{"href":"https:\/\/sig.fmipa.unm.ac.id\/fr\/wp-json\/wp\/v2\/media?parent=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}